{"id":4,"count":14,"description":"","link":"https:\/\/sindicatoquimicosl.org.ar\/wp\/category\/autoridades\/","name":"Representantes Sindicales","slug":"autoridades","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/sindicatoquimicosl.org.ar\/wp\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindicatoquimicosl.org.ar\/wp\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sindicatoquimicosl.org.ar\/wp\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sindicatoquimicosl.org.ar\/wp\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}